{"id":4290,"date":"2020-06-22T20:21:02","date_gmt":"2020-06-22T20:21:02","guid":{"rendered":"https:\/\/cantinagorgo.com\/reviews\/"},"modified":"2021-01-29T12:06:26","modified_gmt":"2021-01-29T12:06:26","slug":"reviews","status":"publish","type":"page","link":"https:\/\/cantinagorgo.com\/en\/reviews\/","title":{"rendered":"Reviews"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4290\" class=\"elementor elementor-4290 elementor-1843\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7b2368 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"d7b2368\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b4a054\" data-id=\"9b4a054\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68a46a4 elementor-widget elementor-widget-image\" data-id=\"68a46a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"545\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/gorgo-azienda-agricola-premi-recensioni-header-1920x545-1.jpg\" class=\"attachment-full size-full wp-image-4395\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/gorgo-azienda-agricola-premi-recensioni-header-1920x545-1.jpg 1920w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/gorgo-azienda-agricola-premi-recensioni-header-1920x545-1-300x85.jpg 300w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/gorgo-azienda-agricola-premi-recensioni-header-1920x545-1-1024x291.jpg 1024w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/gorgo-azienda-agricola-premi-recensioni-header-1920x545-1-768x218.jpg 768w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/gorgo-azienda-agricola-premi-recensioni-header-1920x545-1-1536x436.jpg 1536w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/gorgo-azienda-agricola-premi-recensioni-header-1920x545-1-700x199.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94f8a3c qode_elementor_container_inner elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"94f8a3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a1c489\" data-id=\"3a1c489\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a08ad2 elementor-widget elementor-widget-text-editor\" data-id=\"3a08ad2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>What the say about us<\/h6>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d643b8 elementor-widget elementor-widget-text-editor\" data-id=\"2d643b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Reviews<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61211153 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"61211153\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7a4fd13a\" data-id=\"7a4fd13a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a49b832 elementor-widget elementor-widget-heading\" data-id=\"a49b832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">in<br>Evidence<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a27efc8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6a27efc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7f095196\" data-id=\"7f095196\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35f653c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"35f653c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-left\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3bb02b16 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"3bb02b16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-66582a55\" data-id=\"66582a55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bcc187c elementor-widget elementor-widget-testimonial\" data-id=\"6bcc187c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><p>Il Chiaretto Gorgo punta sul biologico e sfida i vini francesi...<\/p>\n<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-arena-di-verona-logo.jpg\" class=\"attachment-full size-full wp-image-2623\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-arena-di-verona-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-arena-di-verona-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">L' Arena<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-220073a4\" data-id=\"220073a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65bbe90a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"65bbe90a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-left\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-10e44d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"10e44d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-61ba1c2\" data-id=\"61ba1c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebd9e73 elementor-widget elementor-widget-testimonial\" data-id=\"ebd9e73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><p>La conosciamo da svariati anni questa cantina veronese che lavora sul biologico, ma l\u2019ultimo assaggio del loro vino bianco pi\u00f9 espressivo mi ha lasciato di stucco per la grande piacevolezza.<\/p>\n<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/thetomato.ca\/2019-may-june\/wine-maven-may-june-2020\" target=\"_blank\"><img decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-il_golosario-logo.jpg\" class=\"attachment-full size-full wp-image-2619\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-il_golosario-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-il_golosario-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-testimonial-name\" href=\"https:\/\/thetomato.ca\/2019-may-june\/wine-maven-may-june-2020\" target=\"_blank\">Il Golosario<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76b19394 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"76b19394\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-205061b9\" data-id=\"205061b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba7ed90 elementor-widget elementor-widget-bridge_portfolio_list\" data-id=\"ba7ed90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_portfolio_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='projects_holder_outer v5 portfolio_with_space portfolio_standard'>\n        <div class='projects_holder portfolio_main_holder clearfix v5 standard portfolio_full_image portfolio_one_by_one'>\n        \n        <article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Jancis Robinson Redefining Ros\u00e8\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-jancis-robinson-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-jancis-robinson-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/11\/recensioni-jancis-robinson-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_blank\"> Jancis Robinson Redefining Ros\u00e8<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"I Viaggi del Vino\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/10\/recensioni-viaggi-nel-vino-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/10\/recensioni-viaggi-nel-vino-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/10\/recensioni-viaggi-nel-vino-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> I Viaggi del Vino<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"The Tomato Food &#038; Drink\" href=\"https:\/\/thetomato.ca\/2019-may-june\/wine-maven-may-june-2020\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/10\/recensioni-the_tomato_food_drink-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/10\/recensioni-the_tomato_food_drink-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/10\/recensioni-the_tomato_food_drink-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/thetomato.ca\/2019-may-june\/wine-maven-may-june-2020\"  target=\"_blank\"> The Tomato Food &#038; Drink<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Forbes\" href=\"https:\/\/www.forbes.com\/sites\/susangordon\/2019\/08\/09\/rosautoctono-a-new-alliance-to-promote-italys-traditional-pink-wines\/#7934eae64f5e\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-Forbes_logo_black.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-Forbes_logo_black.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-Forbes_logo_black-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.forbes.com\/sites\/susangordon\/2019\/08\/09\/rosautoctono-a-new-alliance-to-promote-italys-traditional-pink-wines\/#7934eae64f5e\"  target=\"_blank\"> Forbes<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Edomon Journal\" href=\"https:\/\/edmontonjournal.com\/life\/food\/wine-column-salvage-summer-with-selection-of-easy-drinking-versatile-wines\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-edmonton-journal-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-edmonton-journal-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-edmonton-journal-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/edmontonjournal.com\/life\/food\/wine-column-salvage-summer-with-selection-of-easy-drinking-versatile-wines\"  target=\"_blank\"> Edomon Journal<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Esquin wine of the Week\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-esquin-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-esquin-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/07\/recensioni-esquin-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Esquin wine of the Week<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Difesa Sostenibile ai fitofagi della vite\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-Consorzio-di-Tutela-del-Custoza-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-Consorzio-di-Tutela-del-Custoza-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-Consorzio-di-Tutela-del-Custoza-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Difesa Sostenibile ai fitofagi della vite<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Fish &#038; Chef\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-fish_chef-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-fish_chef-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-fish_chef-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Fish &#038; Chef<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Wine Align\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-wine-align-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-wine-align-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-wine-align-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Wine Align<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Difesa sostenibile alle tignole della vite\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-consorzio-tutela-vino-custoza-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-consorzio-tutela-vino-custoza-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-consorzio-tutela-vino-custoza-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Difesa sostenibile alle tignole della vite<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Vino in Love\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-vino-in-love-2015-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-vino-in-love-2015-1.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-vino-in-love-2015-1-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Vino in Love<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Winesurf\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-winesurf-logo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-winesurf-logo.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-winesurf-logo-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Winesurf<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Il Sole 24\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-sole-24-ore-2015.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-sole-24-ore-2015.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-sole-24-ore-2015-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Il Sole 24<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"American Airlines\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-american-airlines.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-american-airlines.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-american-airlines-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> American Airlines<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Air Dolomiti\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-airdolomiti-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-airdolomiti-1.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-airdolomiti-1-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Air Dolomiti<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Lufthansa\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-custoza-san-michelin-lufthansa-2a.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-custoza-san-michelin-lufthansa-2a.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-custoza-san-michelin-lufthansa-2a-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_blank\"> Lufthansa<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Lufthansa\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-custoza-san-michelin-lufthansa-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-custoza-san-michelin-lufthansa-1.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-custoza-san-michelin-lufthansa-1-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Lufthansa<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Un vignaiolo di Custoza mette al tappeto il colosso Michelin\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-vinaiolo-custoza-mette-al-tappeto-michelin.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-vinaiolo-custoza-mette-al-tappeto-michelin.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-vinaiolo-custoza-mette-al-tappeto-michelin-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Un vignaiolo di Custoza mette al tappeto il colosso Michelin<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"La contesa sul nome\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-la-contesa-sul-nome.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-la-contesa-sul-nome.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-la-contesa-sul-nome-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> La contesa sul nome<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n<article class='mix portfolio_category_10 default' style=''>\n    \n    \n    \n    \n            <div class=\"item_holder thin_plus_only\">\n\n                    <div class=\"text_holder\">\n        <div class=\"text_holder_outer\">\n            <div class=\"text_holder_inner\">\n                            <span class=\"thin_plus_only_icon\">+<\/span>\n                        <\/div>\n        <\/div>\n    <\/div>\n\n                                    <a itemprop=\"url\" class=\"portfolio_link_class\" title=\"Quel Michelin (in Veneto) che ha lottato per sopravvivere.\" href=\"#\"><\/a>\n                \n                <div style=\"\" class=\"portfolio_shader\"><\/div>\n                <div class=\"image_holder\">\n                    \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-quel-michelin-che-ha-lottato-per-sopravvivere.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-quel-michelin-che-ha-lottato-per-sopravvivere.jpg 250w, https:\/\/cantinagorgo.com\/wp-content\/uploads\/2020\/06\/recensioni-quel-michelin-che-ha-lottato-per-sopravvivere-150x150.jpg 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/span>                <\/div>\n            <\/div>\n\n                <div class='portfolio_description ' style=background-color:#F5F5F5;'>\n\n        \n    <h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"#\"  target=\"_self\"> Quel Michelin (in Veneto) che ha lottato per sopravvivere.<\/a><\/h6>\n\n\n        \n        \n    <\/div>\n\n        \n<\/article>\n        <div class='filler'><\/div>\n            <div class='filler'><\/div>\n            <div class='filler'><\/div>\n            <div class='filler'><\/div>\n            <div class='filler'><\/div>\n        <\/div>\n\n    \n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2474a5c1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"2474a5c1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-100d8286\" data-id=\"100d8286\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bf2c2b0 elementor-widget elementor-widget-heading\" data-id=\"5bf2c2b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/cantinagorgo.com\/guide\/\">Wine Guides<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcbdd03 elementor-widget__width-auto elementor-widget elementor-widget-bridge_button\" data-id=\"fcbdd03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"\/en\/wine-guides\/\" target=\"_self\"  class=\"qbutton  white default\" style=\"\">Discover<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>What the say about us Reviews inEvidence Il Chiaretto Gorgo punta sul biologico e sfida i vini francesi&#8230; L&#8217; Arena La conosciamo da svariati anni questa cantina veronese che lavora sul biologico, ma l\u2019ultimo assaggio del loro vino bianco pi\u00f9 espressivo mi ha lasciato di&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-4290","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cantinagorgo.com\/en\/wp-json\/wp\/v2\/pages\/4290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cantinagorgo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cantinagorgo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cantinagorgo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cantinagorgo.com\/en\/wp-json\/wp\/v2\/comments?post=4290"}],"version-history":[{"count":0,"href":"https:\/\/cantinagorgo.com\/en\/wp-json\/wp\/v2\/pages\/4290\/revisions"}],"wp:attachment":[{"href":"https:\/\/cantinagorgo.com\/en\/wp-json\/wp\/v2\/media?parent=4290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}